{"id":1239,"date":"2020-07-20T08:03:07","date_gmt":"2020-07-20T08:03:07","guid":{"rendered":"https:\/\/www.lesamoureuses.wine\/?p=1239"},"modified":"2020-08-11T09:04:32","modified_gmt":"2020-08-11T09:04:32","slug":"certification-hve-3","status":"publish","type":"post","link":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/","title":{"rendered":"[Certification] HVE 3 &#8211; Haute Valeur Environnementale"},"content":{"rendered":"<p>Le domaine Ch\u00e2teau les Amoureuses vient d\u2019obtenir sa certification HVE 3.<\/p>\n<p>L\u2019agriculture \u00e0 haute valeur environnementale (HVE) est une certification cr\u00e9\u00e9e et encadr\u00e9e par le Minist\u00e8re de l\u2019Agriculture, de l\u2019Agroalimentaire et de la For\u00eat qui vise \u00e0 valoriser les productions issues d\u2019exploitations agricoles qui s\u2019engagent volontairement dans des d\u00e9marches respectueuses de l\u2019environnement.<\/p>\n<p>C\u2019 est une r\u00e9ponse du monde agricole aux attentes de la soci\u00e9t\u00e9 pour une agriculture plus respectueuse de l\u2019environnement qui se base sur des leviers agro\u00e9cologiques.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-212x300.png\" alt=\"\" width=\"491\" height=\"695\" class=\"alignnone wp-image-1275\" srcset=\"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-212x300.png 212w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-450x636.png 450w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-768x1086.png 768w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-724x1024.png 724w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-1086x1536.png 1086w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-350x495.png 350w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-700x990.png 700w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-540x764.png 540w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-1080x1528.png 1080w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-225x318.png 225w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-50x71.png 50w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-480x679.png 480w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-550x778.png 550w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1-600x849.png 600w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/1.png 1414w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-212x300.png\" alt=\"\" width=\"476\" height=\"674\" class=\"alignnone wp-image-1277\" srcset=\"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-212x300.png 212w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-450x636.png 450w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-768x1086.png 768w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-724x1024.png 724w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-1086x1536.png 1086w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-350x495.png 350w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-700x990.png 700w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-540x764.png 540w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-1080x1528.png 1080w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-225x318.png 225w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-50x71.png 50w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-480x679.png 480w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-550x778.png 550w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2-600x849.png 600w, https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/2.png 1414w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le domaine Ch\u00e2teau les Amoureuses vient d\u2019obtenir sa certification HVE 3. L\u2019agriculture \u00e0 haute valeur environnementale (HVE) est une certification cr\u00e9\u00e9e et encadr\u00e9e par le Minist\u00e8re de l\u2019Agriculture, de l\u2019Agroalimentaire et de la For\u00eat qui vise \u00e0 valoriser les productions issues d\u2019exploitations agricoles qui s\u2019engagent volontairement dans des d\u00e9marches respectueuses de l\u2019environnement. C\u2019 est une [\u2026]<\/p>\n","protected":false},"author":415,"featured_media":1240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Certification] HVE 3 - Haute Valeur Environnementale - Les Amoureuses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Certification] HVE 3 - Haute Valeur Environnementale - Les Amoureuses\" \/>\n<meta property=\"og:description\" content=\"Le domaine Ch\u00e2teau les Amoureuses vient d\u2019obtenir sa certification HVE 3. L\u2019agriculture \u00e0 haute valeur environnementale (HVE) est une certification cr\u00e9\u00e9e et encadr\u00e9e par le Minist\u00e8re de l\u2019Agriculture, de l\u2019Agroalimentaire et de la For\u00eat qui vise \u00e0 valoriser les productions issues d\u2019exploitations agricoles qui s\u2019engagent volontairement dans des d\u00e9marches respectueuses de l\u2019environnement. C\u2019 est une [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Amoureuses\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-20T08:03:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-11T09:04:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/HVE-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"2160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Les Amoureuses\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Les Amoureuses\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/\"},\"author\":{\"name\":\"Les Amoureuses\",\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/#\\\/schema\\\/person\\\/a01e4ea175417f30764207e71293f31d\"},\"headline\":\"[Certification] HVE 3 &#8211; Haute Valeur Environnementale\",\"datePublished\":\"2020-07-20T08:03:07+00:00\",\"dateModified\":\"2020-08-11T09:04:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/\"},\"wordCount\":98,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/HVE-3.png\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/\",\"url\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/\",\"name\":\"[Certification] HVE 3 - Haute Valeur Environnementale - Les Amoureuses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/HVE-3.png\",\"datePublished\":\"2020-07-20T08:03:07+00:00\",\"dateModified\":\"2020-08-11T09:04:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/HVE-3.png\",\"contentUrl\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/HVE-3.png\",\"width\":2160,\"height\":2160},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/certification-hve-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Certification] HVE 3 &#8211; Haute Valeur Environnementale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/\",\"name\":\"Les Amoureuses\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/#organization\",\"name\":\"Domaine Les Amoureuses\",\"url\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/LOGO_AMOUREUSES-F.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/LOGO_AMOUREUSES-F.jpg\",\"width\":2339,\"height\":1654,\"caption\":\"Domaine Les Amoureuses\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesamoureuses.wine\\\/en\\\/#\\\/schema\\\/person\\\/a01e4ea175417f30764207e71293f31d\",\"name\":\"Les Amoureuses\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e856133c91e7f65deae6b76b038ba8b514d63a0efa5fe5a4690d2946d9fe1e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e856133c91e7f65deae6b76b038ba8b514d63a0efa5fe5a4690d2946d9fe1e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e856133c91e7f65deae6b76b038ba8b514d63a0efa5fe5a4690d2946d9fe1e5?s=96&d=mm&r=g\",\"caption\":\"Les Amoureuses\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Certification] HVE 3 - Haute Valeur Environnementale - Les Amoureuses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"[Certification] HVE 3 - Haute Valeur Environnementale - Les Amoureuses","og_description":"Le domaine Ch\u00e2teau les Amoureuses vient d\u2019obtenir sa certification HVE 3. L\u2019agriculture \u00e0 haute valeur environnementale (HVE) est une certification cr\u00e9\u00e9e et encadr\u00e9e par le Minist\u00e8re de l\u2019Agriculture, de l\u2019Agroalimentaire et de la For\u00eat qui vise \u00e0 valoriser les productions issues d\u2019exploitations agricoles qui s\u2019engagent volontairement dans des d\u00e9marches respectueuses de l\u2019environnement. C\u2019 est une [\u2026]","og_url":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/","og_site_name":"Les Amoureuses","article_published_time":"2020-07-20T08:03:07+00:00","article_modified_time":"2020-08-11T09:04:32+00:00","og_image":[{"width":2160,"height":2160,"url":"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/HVE-3.png","type":"image\/png"}],"author":"Les Amoureuses","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Les Amoureuses"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/#article","isPartOf":{"@id":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/"},"author":{"name":"Les Amoureuses","@id":"https:\/\/www.lesamoureuses.wine\/en\/#\/schema\/person\/a01e4ea175417f30764207e71293f31d"},"headline":"[Certification] HVE 3 &#8211; Haute Valeur Environnementale","datePublished":"2020-07-20T08:03:07+00:00","dateModified":"2020-08-11T09:04:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/"},"wordCount":98,"publisher":{"@id":"https:\/\/www.lesamoureuses.wine\/en\/#organization"},"image":{"@id":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/HVE-3.png","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/","url":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/","name":"[Certification] HVE 3 - Haute Valeur Environnementale - Les Amoureuses","isPartOf":{"@id":"https:\/\/www.lesamoureuses.wine\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/#primaryimage"},"image":{"@id":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/HVE-3.png","datePublished":"2020-07-20T08:03:07+00:00","dateModified":"2020-08-11T09:04:32+00:00","breadcrumb":{"@id":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/#primaryimage","url":"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/HVE-3.png","contentUrl":"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2020\/07\/HVE-3.png","width":2160,"height":2160},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesamoureuses.wine\/en\/certification-hve-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lesamoureuses.wine\/en\/"},{"@type":"ListItem","position":2,"name":"[Certification] HVE 3 &#8211; Haute Valeur Environnementale"}]},{"@type":"WebSite","@id":"https:\/\/www.lesamoureuses.wine\/en\/#website","url":"https:\/\/www.lesamoureuses.wine\/en\/","name":"Les Amoureuses","description":"","publisher":{"@id":"https:\/\/www.lesamoureuses.wine\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesamoureuses.wine\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.lesamoureuses.wine\/en\/#organization","name":"Domaine Les Amoureuses","url":"https:\/\/www.lesamoureuses.wine\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lesamoureuses.wine\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2023\/08\/LOGO_AMOUREUSES-F.jpg","contentUrl":"https:\/\/www.lesamoureuses.wine\/wp-content\/uploads\/2023\/08\/LOGO_AMOUREUSES-F.jpg","width":2339,"height":1654,"caption":"Domaine Les Amoureuses"},"image":{"@id":"https:\/\/www.lesamoureuses.wine\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.lesamoureuses.wine\/en\/#\/schema\/person\/a01e4ea175417f30764207e71293f31d","name":"Les Amoureuses","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0e856133c91e7f65deae6b76b038ba8b514d63a0efa5fe5a4690d2946d9fe1e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e856133c91e7f65deae6b76b038ba8b514d63a0efa5fe5a4690d2946d9fe1e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e856133c91e7f65deae6b76b038ba8b514d63a0efa5fe5a4690d2946d9fe1e5?s=96&d=mm&r=g","caption":"Les Amoureuses"}}]}},"_links":{"self":[{"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/posts\/1239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/users\/415"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/comments?post=1239"}],"version-history":[{"count":7,"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/posts\/1239\/revisions"}],"predecessor-version":[{"id":1280,"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/posts\/1239\/revisions\/1280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/media\/1240"}],"wp:attachment":[{"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/media?parent=1239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/categories?post=1239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesamoureuses.wine\/en\/wp-json\/wp\/v2\/tags?post=1239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}